{"id":17,"count":8,"description":"","link":"https:\/\/goodforestindonesia.org\/id\/category\/all\/","name":"Semua","slug":"all","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/goodforestindonesia.org\/id\/wp-json\/wp\/v2\/categories\/17","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goodforestindonesia.org\/id\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/goodforestindonesia.org\/id\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/goodforestindonesia.org\/id\/wp-json\/wp\/v2\/posts?categories=17"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}